{"id":1036066,"date":"2024-10-27T08:44:16","date_gmt":"2024-10-27T08:44:16","guid":{"rendered":"https:\/\/thefeminismproject.com\/nicht-kategorisiert\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/"},"modified":"2024-10-27T08:44:16","modified_gmt":"2024-10-27T08:44:16","slug":"wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2","status":"publish","type":"post","link":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/","title":{"rendered":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2."},"content":{"rendered":"<p>Virginia Woolfs Beitr\u00e4ge zur Literatur und zum feministischen Denken haben zunehmend an Bedeutung gewonnen, insbesondere im Zusammenhang mit dem Feminismus der Zweiten Welle, der in den 1960er Jahren aufkam. Woolfs innovative Prosa und ihre provokanten Ideen zu Geschlecht, individueller Handlungsf\u00e4higkeit und gesellschaftlichen Zw\u00e4ngen spiegeln die Themen wider, die von feministischen Aktivistinnen in dieser entscheidenden Zeit vertreten wurden. Dieser Artikel versucht, die vielf\u00e4ltigen Einfl\u00fcsse von Woolf auf den Feminismus der Zweiten Welle zu entschl\u00fcsseln und ihr bleibendes Verm\u00e4chtnis durch eine Untersuchung ihrer Schriften und ihrer gesellschaftspolitischen Implikationen zu enth\u00fcllen.  <\/p>\n<p>Woolfs bahnbrechende Werke, insbesondere &#8222;A Room of One&#8217;s Own&#8220; und &#8222;Mrs Dalloway&#8220;, dienen als Eckpfeiler des feministischen Diskurses. Diese Texte hinterfragen nicht nur die Komplexit\u00e4t der weiblichen Identit\u00e4t, sondern setzen sich auch f\u00fcr die sozio\u00f6konomische Unabh\u00e4ngigkeit ein, die f\u00fcr die Selbstverwirklichung von Frauen unerl\u00e4sslich ist. Damit ist Woolf eine Vorl\u00e4uferin der Ideologien, die sp\u00e4ter den Feminismus der Zweiten Welle pr\u00e4gen sollten, wie etwa die Forderung nach Gleichberechtigung im \u00f6ffentlichen und privaten Bereich.  <\/p>\n<p>Wenn wir uns mit dem Einfluss von Virginia Woolf auf den Feminismus der Zweiten Welle befassen, ist es unerl\u00e4sslich, ihre literarischen Beitr\u00e4ge und deren Resonanz im sp\u00e4teren feministischen Denken sowie das soziokulturelle Milieu, das ihre Perspektiven gepr\u00e4gt hat, zu ber\u00fccksichtigen.<\/p>\n<h2>Woolf in der Landschaft des Feminismus kontextualisieren<\/h2>\n<p>Das fr\u00fche 20. Jahrhundert war eine Zeit des Wandels f\u00fcr Frauen, ausgel\u00f6st durch die Frauenbewegung und die allm\u00e4hliche Ver\u00e4nderung der gesellschaftlichen Normen. Woolfs Schriften entstanden vor dem Hintergrund der aufkeimenden feministischen Ideale. Ihre Argumente betonten die Notwendigkeit f\u00fcr Frauen, sich physische und intellektuelle R\u00e4ume zu schaffen, die ihre pers\u00f6nliche und berufliche Entwicklung erm\u00f6glichen. Dieses Konzept der R\u00e4umlichkeit, das sie in &#8222;A Room of One&#8217;s Own&#8220; formulierte, war eine Metapher f\u00fcr Unabh\u00e4ngigkeit und Kreativit\u00e4t und diente den feministischen Bewegungen, die Jahrzehnte sp\u00e4ter an Schwung gewinnen sollten, als Ankn\u00fcpfungspunkt.   <\/p>\n<p>Der Kampf um ein &#8218;Zimmer&#8216; symbolisiert den umfassenderen Kampf um Autonomie und wirtschaftliche Selbstbestimmung und spiegelt die Betonung der Zweiten Welle wider, dass die Befreiung der Frau nicht nur politische Rechte, sondern auch pers\u00f6nliche und soziale Freiheiten umfasst. Indem sie Frauen dazu aufforderte, finanzielle Unabh\u00e4ngigkeit anzustreben, legte Woolf den Grundstein f\u00fcr die feministischen Wirtschaftstheorien, die in den 1970er Jahren an Bedeutung gewinnen sollten. <\/p>\n<h2>Patriarchale Normen durch Erz\u00e4hlungen in Frage stellen<\/h2>\n<p>Woolfs Erz\u00e4hlstil war f\u00fcr ihre Zeit radikal. Sie bevorzugte Techniken des Bewusstseinsstroms, die eine vielschichtige Erforschung des weiblichen Bewusstseins erm\u00f6glichten. Diese Komplexit\u00e4t wurde zum Sinnbild der feministischen Bewegung, die versuchte, die unterschiedlichen Erfahrungen von Frauen in einer patriarchalischen Gesellschaft in Einklang zu bringen. Anhand von Figuren wie Clarissa Dalloway und Septimus Warren Smith in &#8222;Mrs. Dalloway&#8220; veranschaulichte Woolf die inneren K\u00e4mpfe von Frauen gegen gesellschaftliche Erwartungen und die Auswirkungen der Stigmatisierung psychischer Erkrankungen und griff damit Themen auf, die Feministinnen der Zweiten Welle sp\u00e4ter in einem breiteren gesellschaftspolitischen Kontext enth\u00fcllen w\u00fcrden.  <\/p>\n<p>Dar\u00fcber hinaus sezierte sie in ihren Essays h\u00e4ufig die durch Geschlechterrollen auferlegten Beschr\u00e4nkungen. In &#8222;Three Guineas&#8220; zum Beispiel kritisiert Woolf die tief verwurzelte Frauenfeindlichkeit in Bildungseinrichtungen und Berufen, was mit dem Eintreten der Zweiten Welle f\u00fcr die Rechte der Frauen am Arbeitsplatz und der Behauptung der Pr\u00e4senz von Frauen in traditionell von M\u00e4nnern beherrschten Bereichen \u00fcbereinstimmt. Dies spiegelt den Kampf der Feministinnen gegen systemische Unterdr\u00fcckung und Sexismus wider, die sich f\u00fcr die Gleichberechtigung in Bildung und Beruf einsetzen.  <\/p>\n<h2>Die Intersektionalit\u00e4t des Woolf&#8217;schen Feminismus<\/h2>\n<p>W\u00e4hrend der Feminismus der Zweiten Welle oft f\u00fcr seine Fokussierung auf wei\u00dfe Frauen der Mittelklasse kritisiert wird, zeigen Woolfs Schriften ein fr\u00fches Bewusstsein f\u00fcr die Intersektionalit\u00e4t, die sp\u00e4ter f\u00fcr den feministischen Diskurs grundlegend sein sollte. Ihre Reflexionen \u00fcber die Klasse, wie sie in &#8222;Zum Leuchtturm&#8220; dargestellt werden, offenbaren die Komplexit\u00e4t, die geschlechtsspezifischen Erfahrungen innewohnt. Durch die Darstellung eines Spektrums von Charakteren mit unterschiedlichem sozialem Status gab sie einen Vorgeschmack auf die Notwendigkeit der Inklusion innerhalb der feministischen Bewegungen und forderte die Aktivistinnen auf, die Vielfalt der Erfahrungen von Frauen in verschiedenen Gesellschaftsschichten zu ber\u00fccksichtigen. Diese Nuance findet sich auch in den Schriften vieler Feministinnen der Zweiten Welle wieder, die einen intersektionellen Ansatz verfolgten, der Ethnie, Klasse und Sexualit\u00e4t in ihrem Streben nach Gleichberechtigung ber\u00fccksichtigte.   <\/p>\n<h2>Die Neuinterpretation der weiblichen Identit\u00e4t in der Moderne<\/h2>\n<p>Ein weiterer wichtiger Aspekt von Woolfs Einfluss liegt in ihrer Erforschung der weiblichen Identit\u00e4t inmitten der Zw\u00e4nge der Moderne. Woolf artikulierte die Identit\u00e4tskrise, mit der Frauen konfrontiert waren, als sie sich durch die soziokulturellen Ver\u00e4nderungen des fr\u00fchen 20. Jahrhunderts bewegten. Das Streben ihrer Figuren nach Erf\u00fcllung verdeutlichte die existenziellen Dilemmata, die mit der Rolle der Frau in der Gesellschaft verbunden sind, was Parallelen zum Streben des Feminismus der Zweiten Welle nach Selbstdefinition und dem Recht auf Selbstbestimmung aufweist.  <\/p>\n<p>Diese Betonung der Identit\u00e4t l\u00e4sst sich auf die Grunds\u00e4tze der Bewusstseinsbildung zur\u00fcckf\u00fchren &#8211; eine Schl\u00fcsselkomponente des Feminismus der Zweiten Welle -, die Frauen dazu ermutigte, ihre individuellen Erfahrungen zu teilen, um so Solidarit\u00e4t und Verst\u00e4ndnis innerhalb der feministischen Bewegung zu f\u00f6rdern. Woolfs literarische Erkundung fragmentierter Identit\u00e4ten diente somit als Vorl\u00e4ufer f\u00fcr die erz\u00e4hlerische R\u00fcckgewinnung, die einen Gro\u00dfteil des nachfolgenden feministischen Diskurses kennzeichnete. <\/p>\n<h2>Woolf als Katalysator f\u00fcr feministische Literatur<\/h2>\n<p>Die literarische Bewegung, die w\u00e4hrend der Zweiten Welle aufbl\u00fchte, wurde stark von Woolfs innovativem Ansatz des Geschichtenerz\u00e4hlens beeinflusst. Viele feministische Schriftstellerinnen betrachteten sie als ein Leuchtfeuer der Inspiration und \u00fcbernahmen und interpretierten ihre Themen der Autonomie, der existenziellen Krise und der psychologischen K\u00e4mpfe von Frauen. Simone de Beauvoir und Bell Hooks griffen Woolfs Gedanken auf und untersuchten die geschlechtsspezifische Existenz, die Machtdynamik und die gesellschaftlichen Strukturen.  <\/p>\n<p>Dieses literarische Verm\u00e4chtnis schuf eine Verbindung zwischen feministischen Schriftstellerinnen \u00fcber Generationen hinweg und schuf einen Teppich feministischer Literatur, der die gelebten Erfahrungen von Frauen durch eine Reihe von Erz\u00e4hlformen zu artikulieren versuchte. Woolfs Betonung des subjektiven Charakters der Erfahrung wurde zu einem notwendigen Element der feministischen Literatur und inspirierte Aktivistinnen und Schriftstellerinnen gleicherma\u00dfen, die soziopolitische Landschaft, in der Frauen leben, auszudr\u00fccken, zu kritisieren und zu analysieren. <\/p>\n<h2>Zeitgen\u00f6ssischer Nachhall von Woolfs Ideen<\/h2>\n<p>Der Einfluss von Virginia Woolf geht \u00fcber ihre unmittelbaren literarischen Beitr\u00e4ge hinaus; ihre Gedanken klingen im zeitgen\u00f6ssischen feministischen Denken und Aktivismus nach. W\u00e4hrend sich die Diskussionen \u00fcber Geschlechtsidentit\u00e4t, psychische Gesundheit und Intersektionalit\u00e4t weiterentwickeln, bleiben Woolfs Erkenntnisse weiterhin relevant. Moderne Feministinnen st\u00fctzen sich auf ihre Werke, um f\u00fcr systemische Ver\u00e4nderungen einzutreten, denn sie wissen, dass der Kampf f\u00fcr die Gleichstellung der Geschlechter vielschichtig und kontinuierlich ist. Ihre F\u00e4higkeit, die Nuancen der Erfahrungen von Frauen zu erfassen, erinnert uns eindringlich an den fortw\u00e4hrenden Kampf um Handlungsf\u00e4higkeit und Repr\u00e4sentation in einer Welt, die die verschiedenen Stimmen oft \u00fcbersieht.   <\/p>\n<h2>Schlussfolgerung: Das bleibende Verm\u00e4chtnis von Virginia Woolf<\/h2>\n<p>Zusammenfassend l\u00e4sst sich sagen, dass der Einfluss von Virginia Woolf auf den Feminismus der Zweiten Welle sowohl tiefgreifend als auch vielf\u00e4ltig ist. Ihre literarischen Innovationen und ihre scharfe Gesellschaftskritik ebneten den Weg f\u00fcr ein umfassendes Verst\u00e4ndnis von Frauenthemen, das \u00fcber die Grenzen von Zeit und Kontext hinausgeht. Woolfs Beharren auf der Notwendigkeit wirtschaftlicher Unabh\u00e4ngigkeit, ihre Infragestellung patriarchalischer Normen und ihre Erforschung der Identit\u00e4t machen sie zu einer wegweisenden Figur des feministischen Denkens. Ihr Verm\u00e4chtnis besteht in den anhaltenden Dialogen \u00fcber die Rechte und die Handlungsf\u00e4higkeit von Frauen fort und ermutigt nachfolgende Generationen, das Streben nach Gleichberechtigung und Anerkennung in allen Bereichen des Lebens fortzusetzen.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Virginia Woolfs Beitr\u00e4ge zur Literatur und zum feministischen Denken haben zunehmend an Bedeutung gewonnen, insbesondere im Zusammenhang mit dem Feminismus der Zweiten Welle, der in den 1960er Jahren aufkam. Woolfs innovative Prosa und ihre provokanten Ideen zu Geschlecht, individueller Handlungsf\u00e4higkeit und gesellschaftlichen Zw\u00e4ngen spiegeln die Themen wider, die von feministischen Aktivistinnen in dieser entscheidenden Zeit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1010249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82],"tags":[],"class_list":{"0":"post-1036066","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hervorgehoben"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie einflussreich war Virginia Woolf auf den Feminismus der 2.<\/title>\n<meta name=\"description\" content=\"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.\" \/>\n<meta property=\"og:description\" content=\"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/\" \/>\n<meta property=\"og:site_name\" content=\"thefeminismproject.com\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/matawanitamag\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-27T08:44:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaquimma Anna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaquimma Anna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/\"},\"author\":{\"name\":\"Joaquimma Anna\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#\\\/schema\\\/person\\\/d2d84f0918ac04ca2b9f5b912890ad51\"},\"headline\":\"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.\",\"datePublished\":\"2024-10-27T08:44:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/\"},\"wordCount\":1294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tu-1enzvpmrnkb945.jpg\",\"articleSection\":[\"Hervorgehoben\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/\",\"name\":\"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tu-1enzvpmrnkb945.jpg\",\"datePublished\":\"2024-10-27T08:44:16+00:00\",\"description\":\"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tu-1enzvpmrnkb945.jpg\",\"contentUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/tu-1enzvpmrnkb945.jpg\",\"width\":440,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/hervorgehoben\\\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/\",\"name\":\"thefeminismproject.com\",\"description\":\"Popular culture with a feminist twist | let&#039;s talk about things that matter (news that feels right)\",\"publisher\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#organization\",\"name\":\"thefeminismproject.com\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/pexels-vazhnik-7561648.jpg\",\"contentUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/pexels-vazhnik-7561648.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"thefeminismproject.com\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/#\\\/schema\\\/person\\\/d2d84f0918ac04ca2b9f5b912890ad51\",\"name\":\"Joaquimma Anna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"caption\":\"Joaquimma Anna\"},\"description\":\"Hi my name Joaquimma Anna, and let's tumble down the rabbit hole of thought! At thefeminismproject.com, this blog is a whimsical carnival of ideas. As a mischievous feminism activist, I'm here to juggle the narratives of women. This project? A delightful escapade into the absurdities and splendors of our world. Expect the unexpected!\",\"sameAs\":[\"http:\\\/\\\/thefeminismproject.com\",\"https:\\\/\\\/www.facebook.com\\\/matawanitamag\",\"https:\\\/\\\/www.instagram.com\\\/bsungkawa\\\/?hl=en\"],\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/de\\\/author\\\/bella-sungkawa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.","description":"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/","og_locale":"de_DE","og_type":"article","og_title":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.","og_description":"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.","og_url":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/","og_site_name":"thefeminismproject.com","article_author":"https:\/\/www.facebook.com\/matawanitamag","article_published_time":"2024-10-27T08:44:16+00:00","og_image":[{"width":440,"height":601,"url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg","type":"image\/jpeg"}],"author":"Joaquimma Anna","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joaquimma Anna","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#article","isPartOf":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/"},"author":{"name":"Joaquimma Anna","@id":"https:\/\/thefeminismproject.com\/de\/#\/schema\/person\/d2d84f0918ac04ca2b9f5b912890ad51"},"headline":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.","datePublished":"2024-10-27T08:44:16+00:00","mainEntityOfPage":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/"},"wordCount":1294,"commentCount":0,"publisher":{"@id":"https:\/\/thefeminismproject.com\/de\/#organization"},"image":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#primaryimage"},"thumbnailUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg","articleSection":["Hervorgehoben"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/","url":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/","name":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2.","isPartOf":{"@id":"https:\/\/thefeminismproject.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#primaryimage"},"image":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#primaryimage"},"thumbnailUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg","datePublished":"2024-10-27T08:44:16+00:00","description":"Der Einfluss von Virginia Woolf? Sie spielen ihren Einfluss herunter. Wir enth\u00fcllen die Macht, die sie zu verbergen versuchen. Akzeptieren Sie nicht l\u00e4nger ihre L\u00fcgen, sondern verlangen Sie die vollst\u00e4ndige Geschichte.","breadcrumb":{"@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#primaryimage","url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg","contentUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/tu-1enzvpmrnkb945.jpg","width":440,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/thefeminismproject.com\/de\/hervorgehoben\/wie-einflussreich-war-virginia-woolf-auf-den-feminismus-der-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thefeminismproject.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Wie einflussreich war Virginia Woolf auf den Feminismus der 2."}]},{"@type":"WebSite","@id":"https:\/\/thefeminismproject.com\/de\/#website","url":"https:\/\/thefeminismproject.com\/de\/","name":"thefeminismproject.com","description":"Popular culture with a feminist twist | let&#039;s talk about things that matter (news that feels right)","publisher":{"@id":"https:\/\/thefeminismproject.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefeminismproject.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/thefeminismproject.com\/de\/#organization","name":"thefeminismproject.com","url":"https:\/\/thefeminismproject.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/thefeminismproject.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/pexels-vazhnik-7561648.jpg","contentUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/pexels-vazhnik-7561648.jpg","width":2500,"height":1667,"caption":"thefeminismproject.com"},"image":{"@id":"https:\/\/thefeminismproject.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/thefeminismproject.com\/de\/#\/schema\/person\/d2d84f0918ac04ca2b9f5b912890ad51","name":"Joaquimma Anna","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","caption":"Joaquimma Anna"},"description":"Hi my name Joaquimma Anna, and let's tumble down the rabbit hole of thought! At thefeminismproject.com, this blog is a whimsical carnival of ideas. As a mischievous feminism activist, I'm here to juggle the narratives of women. This project? A delightful escapade into the absurdities and splendors of our world. Expect the unexpected!","sameAs":["http:\/\/thefeminismproject.com","https:\/\/www.facebook.com\/matawanitamag","https:\/\/www.instagram.com\/bsungkawa\/?hl=en"],"url":"https:\/\/thefeminismproject.com\/de\/author\/bella-sungkawa\/"}]}},"_links":{"self":[{"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/posts\/1036066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/comments?post=1036066"}],"version-history":[{"count":0,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/posts\/1036066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/media\/1010249"}],"wp:attachment":[{"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/media?parent=1036066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/categories?post=1036066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefeminismproject.com\/de\/wp-json\/wp\/v2\/tags?post=1036066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}