{"id":1039286,"date":"2025-04-02T05:27:06","date_gmt":"2025-04-02T05:27:06","guid":{"rendered":"https:\/\/thefeminismproject.com\/non-categorise\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/"},"modified":"2025-04-02T05:27:06","modified_gmt":"2025-04-02T05:27:06","slug":"feminisme-et-anorexie-lutte-contre-le-corps-norme","status":"publish","type":"post","link":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/","title":{"rendered":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?"},"content":{"rendered":"<p>Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s&rsquo;entrelacent dans une danse tragique, un tissage de luttes et de souffrances. Loin d&rsquo;\u00eatre des anecdotes isol\u00e9es, ces deux r\u00e9alit\u00e9s sont des \u00e9chos d&rsquo;un m\u00eame cri : celui des corps norm\u00e9s, contraints \u00e0 une perfection inatteignable, \u00e0 l&rsquo;image d&rsquo;un tableau o\u00f9 seules les silhouettes sans imperfections sont c\u00e9l\u00e9br\u00e9es. C&rsquo;est une qu\u00eate d\u2019identit\u00e9, mais aussi une guerre contre un mod\u00e8le qui \u00e9touffe, qui r\u00e9duit les femmes \u00e0 des carcasses, \u00e0 des chiffres sur une balance.<\/p>\n<p>Parlons des corps. Ces entit\u00e9s qui devraient \u00eatre un espace de libert\u00e9, de plaisir et d&rsquo;amour-propre se transforment souvent en champs de bataille. L\u2019anorexie, souvent per\u00e7ue comme une r\u00e9bellion contre la soci\u00e9t\u00e9, se r\u00e9v\u00e8le \u00eatre un mal qui s\u2019insinue dans la chair, solidifiant des attentes irr\u00e9alistes. Elle est le sympt\u00f4me d\u2019une soci\u00e9t\u00e9 qui cultive un ideal inaccessibles, o\u00f9 les femmes sont en permanence jug\u00e9es sur leur apparence.<br \/> La m\u00e9taphore du corps comme un champ de fleurs sauvages est ici pertinente : dans un tel espace, la biodiversit\u00e9 est c\u00e9l\u00e9br\u00e9e, et chaque fleur, unique, apporte sa beaut\u00e9. Pourtant, l\u2019anorexie agit comme un fauve carnivore, rendant la flore homog\u00e8ne, \u00e9laguant autour d&rsquo;elle tout ce qui d\u00e9roge \u00e0 la norme.<\/p>\n<p>La lutte contre les corps norm\u00e9s est une bataille de longue haleine. Les f\u00e9ministes ne se battent pas seulement pour des droits \u00e9gaux, mais \u00e9galement pour l&rsquo;autonomie corporelle. Quel autre choix que celui de reconstruire notre image collective pour d\u00e9fier cette tyrannie ? Le f\u00e9minisme doit revendiquer un espace o\u00f9 chaque corps, quels que soient ses formes, ses tailles, ses imperfections, est accueilli, c\u00e9l\u00e9br\u00e9. Ce mouvement se doit de d\u00e9noncer les standards de beaut\u00e9 impos\u00e9s par la soci\u00e9t\u00e9 : ils ne sont que des mirages, des pi\u00e8ges tendus aux femmes soucieuses de leur apparence.<\/p>\n<p>R\u00e9fl\u00e9chissons \u00e0 ces repr\u00e9sentations mediatiques, les mannequins squelettiques, les influenceurs dont les photos retouch\u00e9es pullulent sur les r\u00e9seaux sociaux. Leurs images sont des troph\u00e9es, mais \u00e0 quel prix ? Les jeunes femmes int\u00e8grent ces images dans leurs esprits comme autant de normes \u00e0 respecter, menant \u00e0 un d\u00e9clin psychologique qui favorise des troubles alimentaires. Les corps sont alors non seulement des cibles, mais des objets de d\u00e9valorisation. L\u2019anorexie, ce cri silencieux, devient une r\u00e9ponse \u00ab\u00a0, une lutte \u2013 mais une lutte qui se retourne contre soi.<\/p>\n<p>Il est crucial d\u2019\u00e9tudier le divorce entre la r\u00e9alit\u00e9 corporelle et la fantaisie impos\u00e9e. Quelle est l\u2019origine de cette obsession pour la minceur ? Elle ne peut \u00eatre dissoci\u00e9e de l\u2019\u00e9conomie du d\u00e9sir, un syst\u00e8me o\u00f9 le corps f\u00e9minin est commodifi\u00e9 et son pouvoir \u00e9rotiquement exploit\u00e9. L&rsquo;anorexie entre alors en sc\u00e8ne comme un d\u00e9fi, un acte de r\u00e9bellion, mais c\u2019est aussi une prison. Paradoxalement, cette lutte se transforme en ali\u00e9nation, enquiquinant l&rsquo;id\u00e9e m\u00eame de libert\u00e9. Les militantes doivent donc faire face \u00e0 une double exigence : revendiquer leur droit \u00e0 l\u2019autonomie tout en d\u00e9construisant cette id\u00e9ologie destructrice autour des corps.<\/p>\n<p>C&rsquo;est dans cette confrontation que le f\u00e9minisme peut se r\u00e9inventer. En int\u00e9grant des r\u00e9cits pluriels, il devient une caisse de r\u00e9sonance pour celles qui vivent dans l&rsquo;ombre des normes, qui luttent contre les d\u00e9mons de l&rsquo;anorexie. Un mouvement authentique doit cr\u00e9er des ponts, embrasser la diversit\u00e9 des corps et des exp\u00e9riences. Qui sommes-nous si nous oublions les voix de celles qui souffrent ? Il en va de la responsabilit\u00e9 collective de b\u00e2tir un discours d\u00e9colonis\u00e9 des normes oppressives.<\/p>\n<p>En puissance, la solidarit\u00e9 f\u00e9ministe doit s\u2019\u00e9riger comme un bastion contre l\u2019oppression des corps. C\u00e9l\u00e9brer les corps imparfaits, ceux qui ne r\u00e9pondent pas aux canons en vigueur, n\u00e9cessite audace et volont\u00e9. C\u2019est en usant de cette passion que l\u2019on peut panser les blessures que la soci\u00e9t\u00e9 inflige \u00e0 ceux qui osent s\u2019\u00e9carter des st\u00e9r\u00e9otypes. Transformer le regard que l\u2019on pose sur soi d\u00e9poli ces \u00e9chos de souffrance. Faire de l&rsquo;anorexie une voix dans la chorale du f\u00e9minisme est un moyen de radicaliser la lutte, de refuser les diktats, et de revendiquer les histoires cach\u00e9es.<\/p>\n<p>Ainsi, le f\u00e9minisme et l&rsquo;anorexie engagent une discussion dynamique, une remise en question permanente des valeurs culturelles qui pr\u00e9valent. Pour toutes celles qui ont cru qu&rsquo;en se rendant invisibles, elles seraient accept\u00e9es, il est temps de reprendre le contr\u00f4le. Disons-le haut et fort : chaque corps raconte une histoire. Nourrissons cette plurivocit\u00e9 au sein du f\u00e9minisme, brisons les cha\u00eenes des corps norm\u00e9s. C&rsquo;est seulement ainsi que nous pourrons b\u00e2tir un avenir o\u00f9 l\u2019identit\u00e9 de chaque femme est c\u00e9l\u00e9br\u00e9e, o\u00f9 elle n\u2019est plus synonyme de lutte, mais de pl\u00e9nitude.<\/p>\n<p>En conclusion, la bataille contre l\u2019anorexie \u00e0 travers le prisme du f\u00e9minisme ne devrait pas \u00eatre un combat solitaire. Elle exige une solidarit\u00e9 fervente et une conscience collective. Seule une approche inclusive permettra de d\u00e9construire les st\u00e9r\u00e9otypes, de c\u00e9l\u00e9brer l&rsquo;unicit\u00e9 de chaque corps et de mettre fin \u00e0 cette tyrannie opaque qui nous contraint \u00e0 \u00eatre moins que nous le sommes. Il est temps de revendiquer notre droit \u00e0 la beaut\u00e9 sous toutes ses formes, de briser les normes et de red\u00e9finir ce que signifie \u00eatre une femme dans notre monde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s&rsquo;entrelacent dans une danse tragique, un tissage de luttes et de souffrances. Loin d&rsquo;\u00eatre des anecdotes isol\u00e9es, ces deux r\u00e9alit\u00e9s sont des \u00e9chos d&rsquo;un m\u00eame cri : celui des corps norm\u00e9s, contraints \u00e0 une perfection inatteignable, \u00e0 l&rsquo;image d&rsquo;un tableau o\u00f9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1036334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":{"0":"post-1039286","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-en-vedette"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?<\/title>\n<meta name=\"description\" content=\"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s&#039;entrelacent dans une danse tragique, un tissage de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?\" \/>\n<meta property=\"og:description\" content=\"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s&#039;entrelacent dans une danse tragique, un tissage de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/\" \/>\n<meta property=\"og:site_name\" content=\"thefeminismproject.com\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/matawanitamag\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T05:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joaquimma Anna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joaquimma Anna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/\"},\"author\":{\"name\":\"Joaquimma Anna\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#\\\/schema\\\/person\\\/d2d84f0918ac04ca2b9f5b912890ad51\"},\"headline\":\"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?\",\"datePublished\":\"2025-04-02T05:27:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/\"},\"wordCount\":962,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/releve-feministe-scaled-1.jpg\",\"articleSection\":[\"En vedette\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/\",\"name\":\"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/releve-feministe-scaled-1.jpg\",\"datePublished\":\"2025-04-02T05:27:06+00:00\",\"description\":\"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s'entrelacent dans une danse tragique, un tissage de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/releve-feministe-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/releve-feministe-scaled-1.jpg\",\"width\":2048,\"height\":1448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/en-vedette\\\/feminisme-et-anorexie-lutte-contre-le-corps-norme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/\",\"name\":\"thefeminismproject.com\",\"description\":\"Popular culture with a feminist twist | let&#039;s talk about things that matter (news that feels right)\",\"publisher\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#organization\",\"name\":\"thefeminismproject.com\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/pexels-vazhnik-7561648.jpg\",\"contentUrl\":\"https:\\\/\\\/thefeminismproject.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/pexels-vazhnik-7561648.jpg\",\"width\":2500,\"height\":1667,\"caption\":\"thefeminismproject.com\"},\"image\":{\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/#\\\/schema\\\/person\\\/d2d84f0918ac04ca2b9f5b912890ad51\",\"name\":\"Joaquimma Anna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g\",\"caption\":\"Joaquimma Anna\"},\"description\":\"Hi my name Joaquimma Anna, and let's tumble down the rabbit hole of thought! At thefeminismproject.com, this blog is a whimsical carnival of ideas. As a mischievous feminism activist, I'm here to juggle the narratives of women. This project? A delightful escapade into the absurdities and splendors of our world. Expect the unexpected!\",\"sameAs\":[\"http:\\\/\\\/thefeminismproject.com\",\"https:\\\/\\\/www.facebook.com\\\/matawanitamag\",\"https:\\\/\\\/www.instagram.com\\\/bsungkawa\\\/?hl=en\"],\"url\":\"https:\\\/\\\/thefeminismproject.com\\\/fr\\\/author\\\/bella-sungkawa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?","description":"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s'entrelacent dans une danse tragique, un tissage de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/","og_locale":"fr_FR","og_type":"article","og_title":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?","og_description":"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s'entrelacent dans une danse tragique, un tissage de","og_url":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/","og_site_name":"thefeminismproject.com","article_author":"https:\/\/www.facebook.com\/matawanitamag","article_published_time":"2025-04-02T05:27:06+00:00","og_image":[{"width":2048,"height":1448,"url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg","type":"image\/jpeg"}],"author":"Joaquimma Anna","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Joaquimma Anna","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#article","isPartOf":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/"},"author":{"name":"Joaquimma Anna","@id":"https:\/\/thefeminismproject.com\/fr\/#\/schema\/person\/d2d84f0918ac04ca2b9f5b912890ad51"},"headline":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?","datePublished":"2025-04-02T05:27:06+00:00","mainEntityOfPage":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/"},"wordCount":962,"commentCount":0,"publisher":{"@id":"https:\/\/thefeminismproject.com\/fr\/#organization"},"image":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#primaryimage"},"thumbnailUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg","articleSection":["En vedette"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/","url":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/","name":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?","isPartOf":{"@id":"https:\/\/thefeminismproject.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#primaryimage"},"image":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#primaryimage"},"thumbnailUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg","datePublished":"2025-04-02T05:27:06+00:00","description":"Dans notre soci\u00e9t\u00e9 contemporaine, il est imp\u00e9ratif de comprendre comment le f\u00e9minisme et l\u2019anorexie s'entrelacent dans une danse tragique, un tissage de","breadcrumb":{"@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#primaryimage","url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg","contentUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2025\/04\/releve-feministe-scaled-1.jpg","width":2048,"height":1448},{"@type":"BreadcrumbList","@id":"https:\/\/thefeminismproject.com\/fr\/en-vedette\/feminisme-et-anorexie-lutte-contre-le-corps-norme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thefeminismproject.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"F\u00e9minisme et anorexie : lutte contre le corps norm\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/thefeminismproject.com\/fr\/#website","url":"https:\/\/thefeminismproject.com\/fr\/","name":"thefeminismproject.com","description":"Popular culture with a feminist twist | let&#039;s talk about things that matter (news that feels right)","publisher":{"@id":"https:\/\/thefeminismproject.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thefeminismproject.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thefeminismproject.com\/fr\/#organization","name":"thefeminismproject.com","url":"https:\/\/thefeminismproject.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thefeminismproject.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/pexels-vazhnik-7561648.jpg","contentUrl":"https:\/\/thefeminismproject.com\/wp-content\/uploads\/2024\/10\/pexels-vazhnik-7561648.jpg","width":2500,"height":1667,"caption":"thefeminismproject.com"},"image":{"@id":"https:\/\/thefeminismproject.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/thefeminismproject.com\/fr\/#\/schema\/person\/d2d84f0918ac04ca2b9f5b912890ad51","name":"Joaquimma Anna","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d06747db1565e73d68391d596fc2eb15a10a4b4c1864574c454435523af94f1?s=96&d=mm&r=g","caption":"Joaquimma Anna"},"description":"Hi my name Joaquimma Anna, and let's tumble down the rabbit hole of thought! At thefeminismproject.com, this blog is a whimsical carnival of ideas. As a mischievous feminism activist, I'm here to juggle the narratives of women. This project? A delightful escapade into the absurdities and splendors of our world. Expect the unexpected!","sameAs":["http:\/\/thefeminismproject.com","https:\/\/www.facebook.com\/matawanitamag","https:\/\/www.instagram.com\/bsungkawa\/?hl=en"],"url":"https:\/\/thefeminismproject.com\/fr\/author\/bella-sungkawa\/"}]}},"_links":{"self":[{"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/posts\/1039286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/comments?post=1039286"}],"version-history":[{"count":0,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/posts\/1039286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/media\/1036334"}],"wp:attachment":[{"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/media?parent=1039286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/categories?post=1039286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thefeminismproject.com\/fr\/wp-json\/wp\/v2\/tags?post=1039286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}